{"id":2895,"date":"2022-03-30T10:00:00","date_gmt":"2022-03-30T10:00:00","guid":{"rendered":"https:\/\/xcoins.com\/?p=2895"},"modified":"2022-11-09T14:59:50","modified_gmt":"2022-11-09T14:59:50","slug":"quien-es-satoshi-nakamoto","status":"publish","type":"post","link":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/","title":{"rendered":"\u00bfQui\u00e9n es Satoshi Nakamoto?"},"content":{"rendered":"<p>A pesar de ser la primera, m\u00e1s grande y m\u00e1s antigua criptomoneda del mundo, en cierto sentido Bitcoin sigue siendo un misterio debido al anonimato de su creador, Satoshi Nakamoto.<\/p>\r\n<p>Aglutinando una capitalizaci\u00f3n de mercado de m\u00e1s de 1893$ mil millones, a d\u00eda 30 de marzo de 2022, Bitcoin ha demostrado su valor como activo y moneda digital. Sin embargo, los frutos de su \u00e9xito no han sido reclamados por nadie, ya que su inventor conocido por el pseud\u00f3nimo Satoshi Nakamoto, a\u00fan sigue en el m\u00e1s profundo anonimato. Adem\u00e1s, Nakamoto tambi\u00e9n ser\u00eda el creador de blockchain como tecnolog\u00eda descentralizada sobre la que construir contratos inteligentes o criptomonedas. Tampoco ha reclamado esta invenci\u00f3n.<\/p>\r\n<p>\u00bfQui\u00e9n o qu\u00e9 es Satoshi Nakamoto? \u00bfDar\u00e1 alguna vez un paso al frente? \u00bfCu\u00e1l es la raz\u00f3n para permanecer en la sombra? Estas son preguntas que han rodeado a los miembros de la comunidad cripto desde inicios de 2010. Exploremos a continuaci\u00f3n todo lo que sabemos sobre la o el supuesto inventor.<\/p>\r\n<h2>Una cronolog\u00eda del \u00e9xito de Bitcoin<\/h2>\r\n<p>Tal y como ha indicado el propio Nakamoto (se cree que Satoshi Nakamoto es un hombre, por lo que usaremos los pronombres masculinos), \u00e9l empez\u00f3 a trabajar en Bitcoin durante la primavera de 2007. En 2008, Nakamoto comparti\u00f3 la idea con unos cuantos compa\u00f1eros cript\u00f3grafos, incluyendo los creadores de b-money y Hashcash, los cuales fueron prototipos de criptomonedas.<\/p>\r\n<p>En agosto de 2008, se registr\u00f3 un dominio llamado bitcoin.org. En octubre de 2008, Satoshi Nakamoto anunci\u00f3 el lanzamiento de Bitcoin con un whitepaper llamado \u201cBitcoin: A Peer-to-Peer Electronic Cash System\u201d (Bitcoin: Un sistema de dinero electr\u00f3nico de usuario a usuario\u201d.<\/p>\r\n<p>El documento de nueve p\u00e1ginas propuso los beneficios de un sistema monetario electr\u00f3nico sin necesidad de confianza, que puenteaba las instituciones financieras. El documento detallaba el sistema de pares o de igual a igual que Nakamoto hab\u00eda conceptualizado, y que resolver\u00eda el \u201cproblema de doble gasto\u201d (<em>double-spending problem<\/em>) que hab\u00eda existido en las monedas electr\u00f3nicas previas, por el que los usuarios pod\u00edan encontrar maneras de gastar su dinero varias veces fraudulentamente.<\/p>\r\n<p>El 3 de enero de 2009, aproximadamente a las 18:15:05 UTC, el primer Bitcoin de la historia fue minado en el tambi\u00e9n conocido como bloque G\u00e9nesis.<\/p>\r\n<p><a href=\"https:\/\/satoshi.nakamotoinstitute.org\/posts\/p2pfoundation\/1\/\" target=\"_blank\" rel=\"noreferrer noopener\">Una publicaci\u00f3n de Nakamoto en un foro<\/a> del 11 de febrero de 2009 explicaba la inspiraci\u00f3n detr\u00e1s de la creaci\u00f3n de Bitcoin \u2013 la catastr\u00f3fica crisis financiera de 2008. \u201cEl problema ra\u00edz del dinero convencional es toda la confianza que requiere para hacerlo funcionar. Se debe confiar en los bancos para guardar nuestro dinero y transferirlo electr\u00f3nicamente, pero estos lo prestan en olas de burbujas de cr\u00e9dito con apenas una fracci\u00f3n en reserva\u201d.<\/p>\r\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-4787 size-full\" src=\"https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/btc-black-chart-1024x576-1.jpg\" alt=\"Monedas de bitcoin con una gr\u00e1fica ascendente luminosa\" width=\"1024\" height=\"576\" srcset=\"https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/btc-black-chart-1024x576-1.jpg 1024w, https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/btc-black-chart-1024x576-1-300x169.jpg 300w, https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/btc-black-chart-1024x576-1-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\r\n<p>Pese a ser lanzado en 2009, Bitcoin no gan\u00f3 mucha tracci\u00f3n hasta 2010, cuando experiment\u00f3 su primera gran subida de precio desde una fracci\u00f3n de centavo a 0.08$. Bitcoin alcanz\u00f3 por primera vez el valor de 1,000$ en noviembre de 2013 antes de caer por debajo de los 350$ en septiembre de 2017 y tres a\u00f1os despu\u00e9s, Bitcoin alcanz\u00f3 la cifra r\u00e9cord de 20,000$ en diciembre de 2020. Actualmente, a d\u00eda 3 de diciembre de 2021, el precio de un bitcoin es de 55,510$.<\/p>\r\n<h2>\u00bfQui\u00e9n es Satoshi Nakamoto?<\/h2>\r\n<p>Detectives de Internet e investigadores de todo el mundo han unido toda la informaci\u00f3n que tenemos a partir de migajas de los detalles que Nakamoto dej\u00f3 antes de desaparecer en 2011.<\/p>\r\n<p>La mayor\u00eda de las pistas se encuentran en mensajes que public\u00f3 en foros entre 2008 y 2011, concretamente en un foro llamado BitcoinTalk que \u00e9l mismo cre\u00f3 en 2009. Aunque millones de personas han analizado sus posts, estos eran le\u00eddos en su d\u00eda sobre todo por un peque\u00f1o grupo de cript\u00f3grafos y programadores.<\/p>\r\n<p>Satoshi Nakamoto se comunicaba con compa\u00f1eros desarrolladores a trav\u00e9s de email pero no compartir\u00eda ninguna informaci\u00f3n personal, como su ubicaci\u00f3n o nombre real. \u00c9l dijo en una ocasi\u00f3n que era un hombre de 37 a\u00f1os viviendo en Jap\u00f3n, no obstante, la mayor\u00eda de gente cree que eso no fue m\u00e1s que una cortina de humo.<\/p>\r\n<h2>\u00bfEs Nakamoto brit\u00e1nico?<\/h2>\r\n<p><img decoding=\"async\" class=\"aligncenter wp-image-4790 size-full\" src=\"https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/london-1024x683-1.jpg\" alt=\"Fotograf\u00eda del Big Ben en Londres, Reino Unido\" width=\"1024\" height=\"683\" srcset=\"https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/london-1024x683-1.jpg 1024w, https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/london-1024x683-1-300x200.jpg 300w, https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/london-1024x683-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\r\n<p>De hecho, algunos creen que Nakamoto es de o vive en Reino Unido. De los metadatos del bloque G\u00e9nesis, hab\u00eda un titular de The Times (el famoso peri\u00f3dico londinense)\u00a0de ese d\u00eda: \u201c<em>The Times 03\/Jan\/2009 Chancellor on brink of second bailout for banks<\/em>\u201d. Tambi\u00e9n fue detectado que Nakamoto usaba expresiones brit\u00e1nicas como \u201cmaths\u201d en lugar de \u201cmath\u201d y \u201cflat\u201d en lugar de \u201capartment\u201d, la segunda de uso com\u00fan en EEUU. Por \u00faltimo, los investigadores han se\u00f1alado que las horas de publicaci\u00f3n de sus posts coinciden con las horas de luz en Reino Unido.<\/p>\r\n<p>No obstante, mucho de todo esto es especulativo, ya que tambi\u00e9n se cree que Satoshi Nakamoto podr\u00eda ser en realidad un grupo de personas en lugar de un solo individuo.<\/p>\r\n<p>Una de las \u00faltimas comunicaciones conocidas y verificadas de Satoshi Nakamoto fue un breve email el 23 de abril de 2011 a un amigo desarrollador llamado Mike Hearn. Justo cuando Bitcoin estaba empezando a ganar su momento estrella, Nakamoto explic\u00f3 a Hearn que \u00e9l se hab\u00eda \u201cpuesto con otras cosas\u201d, y que sent\u00eda que hab\u00eda dejado el proyecto Bitcoin \u201cen buenas manos\u201d.<\/p>\r\n<h2>Encontrando a Satoshi \u2013 los supuestos creadores de Bitcoin<\/h2>\r\n<p>Durante los \u00faltimos 13 a\u00f1os, un n\u00famero de individuos han sido voluntaria e involuntariamente se\u00f1alados como creadores de Bitcoin. Estos son algunos de los sospechosos m\u00e1s conocidos:<\/p>\r\n<ol type=\"1\">\r\n<li><strong>Dorian Satoshi Nakamoto<\/strong>: En 2014,\u00a0<em>Newsweek<\/em>\u00a0caus\u00f3 una histeria masiva cuando afirm\u00f3 haber localizado al creador de Bitcoin en el sur de California. Un hombre llamado Dorian Satoshi Nakamoto, por entonces un jubilado de 64 a\u00f1os con experiencia previa en ingenier\u00eda, fue perseguido por los reporteros antes de enviar una declaraci\u00f3n a\u00a0<em>Newsweek<\/em>\u00a0dos semanas despu\u00e9s afirmando que no ten\u00eda nada que ver con Bitcoin. Todas las esperanzas de que Dorian Nakamoto hab\u00eda creado Bitcoin se deshicieron con la \u00faltima comunicaci\u00f3n de Satoshi Nakamoto \u2013 o al menos alguien con sus datos de usuario. El 7 de marzo de 2014, reapareci\u00f3 brevemente en el foro de Bitcoin para publicar una simple declaraci\u00f3n: \u201cNo soy Dorian Nakamoto\u201d.<\/li>\r\n<li><strong>Hal Finney<\/strong>: Mucha gente crey\u00f3 que el estimado cript\u00f3grafo Hal Finney era Satoshi Nakamoto porque \u00e9l era uno de las primeras personas en usar Bitcoin. No obstante, Finney neg\u00f3 consistentemente ser el inventor de Bitcoin o conocer a Nakamoto. Falleci\u00f3 en 2014.<\/li>\r\n<li><strong>Peter Thiel<\/strong>: Thiel es un empresario alem\u00e1n conocido por fundar PayPal junto a Elon Musk all\u00e1 por 1998. Ha sido tambi\u00e9n socio fundador de varios fondos de inversi\u00f3n, y a lo largo de su carrera ha invertido en muchas start-ups del sector tecnol\u00f3gico. Pero Thiel desmiente ser Nakamoto, comentando de hecho sobre a d\u00f3nde cree que deber\u00eda dirigirse la <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2021-10-21\/peter-thiel-tells-miami-crowd-where-he-d-look-for-satoshi\" target=\"_blank\" rel=\"noopener\">investigaci\u00f3n<\/a> sobre su paradero.\u00a0<\/li>\r\n<li><strong>Nick Szabo<\/strong>: Otro sospechoso clave es Nick Szabo, un cient\u00edfico inform\u00e1tico y conocido cypherpunk que introdujo los smart contracts por primera vez en los 90s. Los investigadores han asegurado que hay claras similitudes entre el estilo ling\u00fc\u00edstico de Szabo y el de Nakamoto, pero Szabo tambi\u00e9n ha mantenido que \u00e9l no es el creador de Bitcoin.<\/li>\r\n<li><strong>Craig Wright<\/strong>: Craig Wright es un emprendedor australiano que dijo que \u00e9l cre\u00f3 Bitcoin y entreg\u00f3 l\u00edneas de c\u00f3digo como prueba. Aunque uno de los desarrolladores de Bitcoin respald\u00f3 la proclamaci\u00f3n de Wright, el c\u00f3digo fue p\u00fablicamente cuestionado y la declaraci\u00f3n es ampliamente considerada como falsa.<\/li>\r\n<li><strong>Len Sassaman<\/strong>: Len Sassaman fue un famoso cript\u00f3grafo dentro del espacio Bitcoin que tr\u00e1gicamente falleci\u00f3 por suicidio en 2011. Pese a ser americano, Sassaman usaba el mismo ingl\u00e9s brit\u00e1nico que Nakamoto y estuvo viviendo en B\u00e9lgica durante el periodo en el que Bitcoin fue creado, lo que se alinea con las ideas de que Nakamoto viv\u00eda en Europa. Pero, al igual que con otros, la teor\u00eda de Sassaman como autor de BTC no ha sido probada.<\/li>\r\n<li><strong>Elon Musk<\/strong>: Dada la gran fama que ha obtenido Musk en los \u00faltimos a\u00f1os, as\u00ed como su gran inter\u00e9s mostrado por las criptomonedas. Algunas personas tambi\u00e9n han insinuado que este magnate podr\u00eda de hecho estar involucrado con el nacimiento de la cripto. Dado el car\u00e1cter innovador de las empresas de Musk (desde Tesla a SpaceX) uno podr\u00eda creer que esta idea no es tan descabellada. Sin embargo, Musk lo neg\u00f3 en <a href=\"https:\/\/twitter.com\/elonmusk\/status\/935329447594541056?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E935329447594541056%7Ctwgr%5E%7Ctwcon%5Es1_&amp;ref_url=https%3A%2F%2Fwww.moneycontrol.com%2Fnews%2Ftrends%2Felon-musks-conspiracy-theory-tweet-on-bitcoin-founder-satoshi-nakamoto-is-viral-8212261.html\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> en 2017.<\/li>\r\n<\/ol>\r\n<p><img decoding=\"async\" class=\"aligncenter wp-image-4792 size-full\" src=\"https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/satoshi-card-1024x576-1.jpg\" alt=\"Tarjeta de cr\u00e9dito con el nombre de Satoshi Nakamoto bajo monedas Bitcoin\" width=\"1024\" height=\"576\" srcset=\"https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/satoshi-card-1024x576-1.jpg 1024w, https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/satoshi-card-1024x576-1-300x169.jpg 300w, https:\/\/xcoins.com\/wp-content\/uploads\/2021\/12\/satoshi-card-1024x576-1-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\r\n<h2>\u00bfCu\u00e1ntos bitcoins tiene Satoshi Nakamoto?<\/h2>\r\n<p>Esta es una de las preguntas m\u00e1s importantes que uno suele hacerse al pensar en esta persona o grupo creador de Bitcoin. Precisamente, este asunto podr\u00eda tener relaci\u00f3n con su intenci\u00f3n de permanecer en el anonimato. Veamos: el gobierno de Estados Unidos y el FBI han perseguido hist\u00f3ricamente a los individuos que han creado alternativas a monedas federales.<\/p>\r\n<p>Bernard von NotHaus invent\u00f3 una moneda llamada Liberty Dollars en 1998, y en 2011 fue arrestado con cargos federales. Fue <a href=\"https:\/\/archives.fbi.gov\/archives\/charlotte\/press-releases\/2011\/defendant-convicted-of-minting-his-own-currency\" target=\"_blank\" rel=\"noreferrer noopener\">sentenciado<\/a> a seis meses de arresto domiciliario y a tres a\u00f1os de libertad condicional. De forma similar, en 2007, la prometedora divisa digital E-gold fue destruida por el gobierno debido a sospechas de lavado de dinero. Por esa raz\u00f3n, Satoshi Nakamoto podr\u00eda estar protegi\u00e9ndose a s\u00ed mismo de potenciales castigos por haber creado Bitcoin.<\/p>\r\n<p>Por otro lado, el movimiento Bitcoin est\u00e1 protagonizado por la descentralizaci\u00f3n. Se cree que Satoshi Nakamoto posee m\u00e1s de un mill\u00f3n de Bitcoins en monederos inactivos que <strong>valdr\u00edan m\u00e1s de 60$ mil millones de d\u00f3lares<\/strong> seg\u00fan los precios de hoy. Si es desenmascarado o decide mover o usar esos fondos, podr\u00eda desestabilizar la moneda, ya que una porci\u00f3n muy importante estar\u00eda siendo controlada por un solo individuo.<\/p>\r\n<h2>\u00bfQu\u00e9 significa esto para el futuro de Bitcoin?<\/h2>\r\n<p>Aunque muy pocos lo vieron venir en 2008, el inventor de la blockchain descentralizada Satoshi Nakamoto ha revolucionado el sistema financiero. Es justo asumir que revelar su identidad impactar\u00eda el mercado y potencialmente el precio de Bitcoin, no obstante, es dif\u00edcil estimar exactamente qu\u00e9 situaci\u00f3n desencadenar\u00eda ese impacto.<\/p>\r\n<p>Entre tanto, las preguntas sobre su identidad y paradero permanecen sin respuesta desde hace m\u00e1s de 13 a\u00f1os, y nos hemos quedado con Bitcoin como una de las donaciones an\u00f3nimas m\u00e1s generosas de la historia.<\/p>\r\n<p><em>Para mantenerte actualizado sobre todo lo relacionado con las criptomonedas, puedes dar me gusta a Xcoins en\u00a0<a href=\"https:\/\/www.facebook.com\/xcoinsofficial\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>, seguirnos en\u00a0<a href=\"https:\/\/twitter.com\/realxcoins\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/realxcoins\/mycompany\/\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>\u00a0y registrarte en la parte inferior de esta p\u00e1gina para suscribirte.<\/em><\/p>\r\n<h2>Preguntas Frecuentes<\/h2>\r\n\r\n<div class=\"schema-faq wp-block-yoast-faq-block\">\r\n<div id=\"faq-question-1648647196854\" class=\"schema-faq-section\"><strong class=\"schema-faq-question\">\u00bfQui\u00e9n es Satoshi Nakamoto?<\/strong>\r\n<p class=\"schema-faq-answer\">No se sabe qui\u00e9n es el fundador o fundadores de Bitcoin, la primera criptomoneda del mundo. Se han hecho varias elucubraciones, pero a\u00fan no se ha podido verificar ninguna. Su paradero sigue siendo desconocido.<\/p>\r\n<\/div>\r\n<div id=\"faq-question-1648647275583\" class=\"schema-faq-section\"><strong class=\"schema-faq-question\">\u00bfCu\u00e1ntos bitcoins tiene Satoshi Nakamoto?<\/strong>\r\n<p class=\"schema-faq-answer\">Estudiando los primeros bloques de la blockchain en 2009 y 2010, se estima que Satoshi podr\u00eda teneralgo m\u00e1s de 1 mill\u00f3n de bitcoins en monederos inactivos. Esto equivaldr\u00eda a 60$ mil millones.<\/p>\r\n<\/div>\r\n<div id=\"faq-question-1648647493273\" class=\"schema-faq-section\"><strong class=\"schema-faq-question\">\u00bfQui\u00e9n cre\u00f3 la blockchain?<\/strong>\r\n<p class=\"schema-faq-answer\">Pese a que la historia de la tecnolog\u00eda blockchain comienza algo antes, la invenci\u00f3n de la primera blockchain descentralizada se le atribuye a Satoshi Nakamoto, siendo esta la innovadora tecnolog\u00eda en la que se apoyar\u00eda la primera criptomoneda del mundo, Bitcoin. Ser\u00eda entonces Satoshi quien, en 2009, popularizar\u00eda progresivamente esta tecnolog\u00eda as\u00ed como el propio Bitcoin. El &#8216;bit gold&#8217; de Nick Szabo (1998) es un intento previo de conceptualizar lo que Nakamoto llev\u00f3 a la pr\u00e1ctica.<\/p>\r\n<\/div>\r\n<\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>A pesar de ser la primera, m\u00e1s grande y m\u00e1s antigua criptomoneda del mundo, en cierto sentido Bitcoin sigue siendo [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":2862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[758],"tags":[513,624,623],"class_list":["post-2895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academia-2","tag-bitcoin-es","tag-creador","tag-satoshi-nakamoto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfQui\u00e9n es Satoshi Nakamoto? I Xcoins<\/title>\n<meta name=\"description\" content=\"\u00bfQui\u00e9n es Satoshi Nakamoto? Este es el nombre (o pseud\u00f3nimo) de la misteriosa persona o grupo responsable de la creaci\u00f3n de Bitcoin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es Satoshi Nakamoto?\" \/>\n<meta property=\"og:description\" content=\"\u00bfQui\u00e9n es Satoshi Nakamoto? Este es el nombre (o pseud\u00f3nimo) de la misteriosa persona o grupo responsable de la creaci\u00f3n de Bitcoin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/\" \/>\n<meta property=\"og:site_name\" content=\"Xcoins\u2122 Official\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/xcoinsofficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T14:59:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xcoins.com\/wp-content\/uploads\/2022\/01\/satoshi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"xcoins.com Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@realxcoins\" \/>\n<meta name=\"twitter:site\" content=\"@realxcoins\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"xcoins.com Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/\"},\"author\":{\"name\":\"xcoins.com Team\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/4bd2b3071d8ad61c50edb9fa1c2a0ca0\"},\"headline\":\"\u00bfQui\u00e9n es Satoshi Nakamoto?\",\"datePublished\":\"2022-03-30T10:00:00+00:00\",\"dateModified\":\"2022-11-09T14:59:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/\"},\"wordCount\":1964,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xcoins.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/satoshi.jpg\",\"keywords\":[\"bitcoin\",\"creador\",\"satoshi nakamoto\"],\"articleSection\":[\"Academia Cripto\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/\",\"url\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/\",\"name\":\"\u00bfQui\u00e9n es Satoshi Nakamoto? I Xcoins\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xcoins.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/satoshi.jpg\",\"datePublished\":\"2022-03-30T10:00:00+00:00\",\"dateModified\":\"2022-11-09T14:59:50+00:00\",\"description\":\"\u00bfQui\u00e9n es Satoshi Nakamoto? Este es el nombre (o pseud\u00f3nimo) de la misteriosa persona o grupo responsable de la creaci\u00f3n de Bitcoin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647196854\"},{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647275583\"},{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647493273\"}],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xcoins.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/satoshi.jpg\",\"contentUrl\":\"https:\\\/\\\/xcoins.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/satoshi.jpg\",\"width\":1200,\"height\":628,\"caption\":\"The silhouette of an anonymous person in front of a light background.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n es Satoshi Nakamoto?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xcoins.com\\\/es\\\/\",\"name\":\"Xcoins\u2122 Official\",\"description\":\"Buy and Sell Crypto Instantly\",\"publisher\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#organization\",\"name\":\"xcoins.com\",\"url\":\"https:\\\/\\\/xcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xcoins.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/xcoins-logo.png\",\"contentUrl\":\"https:\\\/\\\/xcoins.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/xcoins-logo.png\",\"width\":559,\"height\":559,\"caption\":\"xcoins.com\"},\"image\":{\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/xcoinsofficial\\\/\",\"https:\\\/\\\/x.com\\\/realxcoins\",\"https:\\\/\\\/www.instagram.com\\\/xcoins.hq\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/realxcoins\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/4bd2b3071d8ad61c50edb9fa1c2a0ca0\",\"name\":\"xcoins.com Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/042c4cf76f09e0d0daa41c8bfbb4ed6262ad7095ce06eddc374ce04cb562033a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/042c4cf76f09e0d0daa41c8bfbb4ed6262ad7095ce06eddc374ce04cb562033a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/042c4cf76f09e0d0daa41c8bfbb4ed6262ad7095ce06eddc374ce04cb562033a?s=96&d=mm&r=g\",\"caption\":\"xcoins.com Team\"}},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647196854\",\"position\":1,\"url\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647196854\",\"name\":\"\u00bfQui\u00e9n es Satoshi Nakamoto?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"No se sabe qui\u00e9n es el fundador o fundadores de Bitcoin, la primera criptomoneda del mundo. Se han hecho varias elucubraciones, pero a\u00fan no se ha podido verificar ninguna. Su paradero sigue siendo desconocido.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647275583\",\"position\":2,\"url\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647275583\",\"name\":\"\u00bfCu\u00e1ntos bitcoins tiene Satoshi Nakamoto?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Estudiando los primeros bloques de la blockchain en 2009 y 2010, se estima que Satoshi podr\u00eda teneralgo m\u00e1s de 1 mill\u00f3n de bitcoins en monederos inactivos. Esto equivaldr\u00eda a 60$ mil millones.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647493273\",\"position\":3,\"url\":\"https:\\\/\\\/xcoins.com\\\/es\\\/blog\\\/quien-es-satoshi-nakamoto\\\/#faq-question-1648647493273\",\"name\":\"\u00bfQui\u00e9n cre\u00f3 la blockchain?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Pese a que la historia de la tecnolog\u00eda blockchain comienza algo antes, la invenci\u00f3n de la primera blockchain descentralizada se le atribuye a Satoshi Nakamoto, siendo esta la innovadora tecnolog\u00eda en la que se apoyar\u00eda la primera criptomoneda del mundo, Bitcoin. Ser\u00eda entonces Satoshi quien, en 2009, popularizar\u00eda progresivamente esta tecnolog\u00eda as\u00ed como el propio Bitcoin. El 'bit gold' de Nick Szabo (1998) es un intento previo de conceptualizar lo que Nakamoto llev\u00f3 a la pr\u00e1ctica.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es Satoshi Nakamoto? I Xcoins","description":"\u00bfQui\u00e9n es Satoshi Nakamoto? Este es el nombre (o pseud\u00f3nimo) de la misteriosa persona o grupo responsable de la creaci\u00f3n de Bitcoin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es Satoshi Nakamoto?","og_description":"\u00bfQui\u00e9n es Satoshi Nakamoto? Este es el nombre (o pseud\u00f3nimo) de la misteriosa persona o grupo responsable de la creaci\u00f3n de Bitcoin.","og_url":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/","og_site_name":"Xcoins\u2122 Official","article_publisher":"https:\/\/www.facebook.com\/xcoinsofficial\/","article_published_time":"2022-03-30T10:00:00+00:00","article_modified_time":"2022-11-09T14:59:50+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/xcoins.com\/wp-content\/uploads\/2022\/01\/satoshi.jpg","type":"image\/jpeg"}],"author":"xcoins.com Team","twitter_card":"summary_large_image","twitter_creator":"@realxcoins","twitter_site":"@realxcoins","twitter_misc":{"Escrito por":"xcoins.com Team","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#article","isPartOf":{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/"},"author":{"name":"xcoins.com Team","@id":"https:\/\/xcoins.com\/es\/#\/schema\/person\/4bd2b3071d8ad61c50edb9fa1c2a0ca0"},"headline":"\u00bfQui\u00e9n es Satoshi Nakamoto?","datePublished":"2022-03-30T10:00:00+00:00","dateModified":"2022-11-09T14:59:50+00:00","mainEntityOfPage":{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/"},"wordCount":1964,"commentCount":1,"publisher":{"@id":"https:\/\/xcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#primaryimage"},"thumbnailUrl":"https:\/\/xcoins.com\/wp-content\/uploads\/2022\/01\/satoshi.jpg","keywords":["bitcoin","creador","satoshi nakamoto"],"articleSection":["Academia Cripto"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#respond"]}]},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/","url":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/","name":"\u00bfQui\u00e9n es Satoshi Nakamoto? I Xcoins","isPartOf":{"@id":"https:\/\/xcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#primaryimage"},"image":{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#primaryimage"},"thumbnailUrl":"https:\/\/xcoins.com\/wp-content\/uploads\/2022\/01\/satoshi.jpg","datePublished":"2022-03-30T10:00:00+00:00","dateModified":"2022-11-09T14:59:50+00:00","description":"\u00bfQui\u00e9n es Satoshi Nakamoto? Este es el nombre (o pseud\u00f3nimo) de la misteriosa persona o grupo responsable de la creaci\u00f3n de Bitcoin.","breadcrumb":{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647196854"},{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647275583"},{"@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647493273"}],"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#primaryimage","url":"https:\/\/xcoins.com\/wp-content\/uploads\/2022\/01\/satoshi.jpg","contentUrl":"https:\/\/xcoins.com\/wp-content\/uploads\/2022\/01\/satoshi.jpg","width":1200,"height":628,"caption":"The silhouette of an anonymous person in front of a light background."},{"@type":"BreadcrumbList","@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n es Satoshi Nakamoto?"}]},{"@type":"WebSite","@id":"https:\/\/xcoins.com\/es\/#website","url":"https:\/\/xcoins.com\/es\/","name":"Xcoins\u2122 Official","description":"Buy and Sell Crypto Instantly","publisher":{"@id":"https:\/\/xcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/xcoins.com\/es\/#organization","name":"xcoins.com","url":"https:\/\/xcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/xcoins.com\/wp-content\/uploads\/2022\/01\/xcoins-logo.png","contentUrl":"https:\/\/xcoins.com\/wp-content\/uploads\/2022\/01\/xcoins-logo.png","width":559,"height":559,"caption":"xcoins.com"},"image":{"@id":"https:\/\/xcoins.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/xcoinsofficial\/","https:\/\/x.com\/realxcoins","https:\/\/www.instagram.com\/xcoins.hq\/","https:\/\/www.linkedin.com\/company\/realxcoins\/"]},{"@type":"Person","@id":"https:\/\/xcoins.com\/es\/#\/schema\/person\/4bd2b3071d8ad61c50edb9fa1c2a0ca0","name":"xcoins.com Team","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/042c4cf76f09e0d0daa41c8bfbb4ed6262ad7095ce06eddc374ce04cb562033a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/042c4cf76f09e0d0daa41c8bfbb4ed6262ad7095ce06eddc374ce04cb562033a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/042c4cf76f09e0d0daa41c8bfbb4ed6262ad7095ce06eddc374ce04cb562033a?s=96&d=mm&r=g","caption":"xcoins.com Team"}},{"@type":"Question","@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647196854","position":1,"url":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647196854","name":"\u00bfQui\u00e9n es Satoshi Nakamoto?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"No se sabe qui\u00e9n es el fundador o fundadores de Bitcoin, la primera criptomoneda del mundo. Se han hecho varias elucubraciones, pero a\u00fan no se ha podido verificar ninguna. Su paradero sigue siendo desconocido.","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647275583","position":2,"url":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647275583","name":"\u00bfCu\u00e1ntos bitcoins tiene Satoshi Nakamoto?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Estudiando los primeros bloques de la blockchain en 2009 y 2010, se estima que Satoshi podr\u00eda teneralgo m\u00e1s de 1 mill\u00f3n de bitcoins en monederos inactivos. Esto equivaldr\u00eda a 60$ mil millones.","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647493273","position":3,"url":"https:\/\/xcoins.com\/es\/blog\/quien-es-satoshi-nakamoto\/#faq-question-1648647493273","name":"\u00bfQui\u00e9n cre\u00f3 la blockchain?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Pese a que la historia de la tecnolog\u00eda blockchain comienza algo antes, la invenci\u00f3n de la primera blockchain descentralizada se le atribuye a Satoshi Nakamoto, siendo esta la innovadora tecnolog\u00eda en la que se apoyar\u00eda la primera criptomoneda del mundo, Bitcoin. Ser\u00eda entonces Satoshi quien, en 2009, popularizar\u00eda progresivamente esta tecnolog\u00eda as\u00ed como el propio Bitcoin. El 'bit gold' de Nick Szabo (1998) es un intento previo de conceptualizar lo que Nakamoto llev\u00f3 a la pr\u00e1ctica.","inLanguage":"es"},"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/posts\/2895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/comments?post=2895"}],"version-history":[{"count":0,"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/posts\/2895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/media\/2862"}],"wp:attachment":[{"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/media?parent=2895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/categories?post=2895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xcoins.com\/es\/wp-json\/wp\/v2\/tags?post=2895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}